{"id":30,"count":438,"description":"","link":"https:\/\/vet.purdue.edu\/news\/category\/academics","name":"Academics","slug":"academics","taxonomy":"category","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/vet.purdue.edu\/news\/wp-json\/wp\/v2\/categories\/30","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vet.purdue.edu\/news\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/vet.purdue.edu\/news\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/vet.purdue.edu\/news\/wp-json\/wp\/v2\/posts?categories=30"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}